{"id":45502,"date":"2025-01-24T18:21:01","date_gmt":"2025-01-24T18:21:01","guid":{"rendered":"https:\/\/www.rochester.edu\/commencement\/?page_id=45502"},"modified":"2025-01-29T17:05:27","modified_gmt":"2025-01-29T17:05:27","slug":"class-of-2021","status":"publish","type":"page","link":"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/","title":{"rendered":"Class of 2021"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":82,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-45502","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Class of 2021 - Commencement Weekend<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Class of 2021 - Commencement Weekend\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Commencement Weekend\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T17:05:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rochester.edu\/commencement\/wp-content\/uploads\/2025\/11\/URochester-Link-Preview-Commencement.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/class-of-2021\\\/\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/class-of-2021\\\/\",\"name\":\"Class of 2021 - Commencement Weekend\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/#website\"},\"datePublished\":\"2025-01-24T18:21:01+00:00\",\"dateModified\":\"2025-01-29T17:05:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/class-of-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/class-of-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/class-of-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Class of 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/#website\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/\",\"name\":\"Commencement Weekend\",\"description\":\"University of Rochester\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/#organization\",\"name\":\"University of Rochester\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/meliora-fea-1.png\",\"contentUrl\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/meliora-fea-1.png\",\"width\":1200,\"height\":630,\"caption\":\"University of Rochester\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/commencement\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Class of 2021 - Commencement Weekend","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/","og_locale":"en_US","og_type":"article","og_title":"Class of 2021 - Commencement Weekend","og_url":"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/","og_site_name":"Commencement Weekend","article_modified_time":"2025-01-29T17:05:27+00:00","og_image":[{"url":"https:\/\/www.rochester.edu\/commencement\/wp-content\/uploads\/2025\/11\/URochester-Link-Preview-Commencement.jpg","width":1200,"height":630,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/","url":"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/","name":"Class of 2021 - Commencement Weekend","isPartOf":{"@id":"https:\/\/www.rochester.edu\/commencement\/#website"},"datePublished":"2025-01-24T18:21:01+00:00","dateModified":"2025-01-29T17:05:27+00:00","breadcrumb":{"@id":"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rochester.edu\/commencement\/class-of-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rochester.edu\/commencement\/class-of-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rochester.edu\/commencement\/"},{"@type":"ListItem","position":2,"name":"Class of 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.rochester.edu\/commencement\/#website","url":"https:\/\/www.rochester.edu\/commencement\/","name":"Commencement Weekend","description":"University of Rochester","publisher":{"@id":"https:\/\/www.rochester.edu\/commencement\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rochester.edu\/commencement\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rochester.edu\/commencement\/#organization","name":"University of Rochester","url":"https:\/\/www.rochester.edu\/commencement\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rochester.edu\/commencement\/#\/schema\/logo\/image\/","url":"https:\/\/www.rochester.edu\/commencement\/wp-content\/uploads\/2020\/05\/meliora-fea-1.png","contentUrl":"https:\/\/www.rochester.edu\/commencement\/wp-content\/uploads\/2020\/05\/meliora-fea-1.png","width":1200,"height":630,"caption":"University of Rochester"},"image":{"@id":"https:\/\/www.rochester.edu\/commencement\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rochester.edu\/commencement\/wp-json\/wp\/v2\/pages\/45502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rochester.edu\/commencement\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rochester.edu\/commencement\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rochester.edu\/commencement\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rochester.edu\/commencement\/wp-json\/wp\/v2\/comments?post=45502"}],"version-history":[{"count":6,"href":"https:\/\/www.rochester.edu\/commencement\/wp-json\/wp\/v2\/pages\/45502\/revisions"}],"predecessor-version":[{"id":46372,"href":"https:\/\/www.rochester.edu\/commencement\/wp-json\/wp\/v2\/pages\/45502\/revisions\/46372"}],"wp:attachment":[{"href":"https:\/\/www.rochester.edu\/commencement\/wp-json\/wp\/v2\/media?parent=45502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}