{"id":28292,"date":"2025-02-21T10:38:31","date_gmt":"2025-02-21T15:38:31","guid":{"rendered":"https:\/\/www.rochester.edu\/communications\/?page_id=28292"},"modified":"2025-04-30T10:14:38","modified_gmt":"2025-04-30T14:14:38","slug":"feature-request","status":"publish","type":"page","link":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/","title":{"rendered":"Feature Request"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":14392,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-28292","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feature Request - University Marketing and Communications<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feature Request - University Marketing and Communications\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/\" \/>\n<meta property=\"og:site_name\" content=\"University Marketing and Communications\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T14:14:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rochester.edu\/communications\/wp-content\/uploads\/2025\/10\/URochester-Link-Preview-Marcom-ImageRight.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/resources\\\/web-seo\\\/wordpress-theme\\\/feature-request\\\/\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/resources\\\/web-seo\\\/wordpress-theme\\\/feature-request\\\/\",\"name\":\"Feature Request - University Marketing and Communications\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/#website\"},\"datePublished\":\"2025-02-21T15:38:31+00:00\",\"dateModified\":\"2025-04-30T14:14:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/resources\\\/web-seo\\\/wordpress-theme\\\/feature-request\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/resources\\\/web-seo\\\/wordpress-theme\\\/feature-request\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/resources\\\/web-seo\\\/wordpress-theme\\\/feature-request\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Digital resources\",\"item\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/resources\\\/web-seo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Rochester Core resources\",\"item\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/resources\\\/web-seo\\\/wordpress-theme\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Feature Request\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/#website\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/\",\"name\":\"University Marketing and Communications\",\"description\":\"University of Rochester\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/#organization\",\"name\":\"University Marketing and Communications\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/university-communications.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/university-communications.jpg\",\"width\":1200,\"height\":630,\"caption\":\"University Marketing and Communications\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/communications\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feature Request - University Marketing and Communications","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/","og_locale":"en_US","og_type":"article","og_title":"Feature Request - University Marketing and Communications","og_url":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/","og_site_name":"University Marketing and Communications","article_modified_time":"2025-04-30T14:14:38+00:00","og_image":[{"url":"https:\/\/www.rochester.edu\/communications\/wp-content\/uploads\/2025\/10\/URochester-Link-Preview-Marcom-ImageRight.png","width":1200,"height":630,"type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/","url":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/","name":"Feature Request - University Marketing and Communications","isPartOf":{"@id":"https:\/\/www.rochester.edu\/communications\/#website"},"datePublished":"2025-02-21T15:38:31+00:00","dateModified":"2025-04-30T14:14:38+00:00","breadcrumb":{"@id":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/feature-request\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rochester.edu\/communications\/"},{"@type":"ListItem","position":2,"name":"Resources","item":"https:\/\/www.rochester.edu\/communications\/resources\/"},{"@type":"ListItem","position":3,"name":"Digital resources","item":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/"},{"@type":"ListItem","position":4,"name":"Rochester Core resources","item":"https:\/\/www.rochester.edu\/communications\/resources\/web-seo\/wordpress-theme\/"},{"@type":"ListItem","position":5,"name":"Feature Request"}]},{"@type":"WebSite","@id":"https:\/\/www.rochester.edu\/communications\/#website","url":"https:\/\/www.rochester.edu\/communications\/","name":"University Marketing and Communications","description":"University of Rochester","publisher":{"@id":"https:\/\/www.rochester.edu\/communications\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rochester.edu\/communications\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rochester.edu\/communications\/#organization","name":"University Marketing and Communications","url":"https:\/\/www.rochester.edu\/communications\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rochester.edu\/communications\/#\/schema\/logo\/image\/","url":"https:\/\/www.rochester.edu\/communications\/wp-content\/uploads\/2023\/03\/university-communications.jpg","contentUrl":"https:\/\/www.rochester.edu\/communications\/wp-content\/uploads\/2023\/03\/university-communications.jpg","width":1200,"height":630,"caption":"University Marketing and Communications"},"image":{"@id":"https:\/\/www.rochester.edu\/communications\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/pages\/28292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/comments?post=28292"}],"version-history":[{"count":6,"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/pages\/28292\/revisions"}],"predecessor-version":[{"id":30092,"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/pages\/28292\/revisions\/30092"}],"up":[{"embeddable":true,"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/pages\/14392"}],"wp:attachment":[{"href":"https:\/\/www.rochester.edu\/communications\/wp-json\/wp\/v2\/media?parent=28292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}