{"id":4356,"date":"2025-02-27T11:14:29","date_gmt":"2025-02-27T16:14:29","guid":{"rendered":"https:\/\/www.rochester.edu\/endowment\/?page_id=4356"},"modified":"2025-03-04T11:33:56","modified_gmt":"2025-03-04T16:33:56","slug":"historical-timeline","status":"publish","type":"page","link":"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/","title":{"rendered":"Historical Timeline"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4356","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historical Timeline - Endowment<\/title>\n<meta name=\"description\" content=\"Explore the University of Rochester\u2019s Endowment timeline and discover key milestones that have shaped its growth and impact since its founding.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historical Timeline - Endowment\" \/>\n<meta property=\"og:description\" content=\"Explore the University of Rochester\u2019s Endowment timeline and discover key milestones that have shaped its growth and impact since its founding.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/\" \/>\n<meta property=\"og:site_name\" content=\"Endowment\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-04T16:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rochester.edu\/endowment\/wp-content\/uploads\/2025\/03\/Link-Preview-Endowment.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/historical-timeline\\\/\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/historical-timeline\\\/\",\"name\":\"Historical Timeline - Endowment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/#website\"},\"datePublished\":\"2025-02-27T16:14:29+00:00\",\"dateModified\":\"2025-03-04T16:33:56+00:00\",\"description\":\"Explore the University of Rochester\u2019s Endowment timeline and discover key milestones that have shaped its growth and impact since its founding.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/historical-timeline\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/historical-timeline\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/historical-timeline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historical Timeline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/#website\",\"url\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/\",\"name\":\"Endowment University of Rochester\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rochester.edu\\\/endowment\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historical Timeline - Endowment","description":"Explore the University of Rochester\u2019s Endowment timeline and discover key milestones that have shaped its growth and impact since its founding.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/","og_locale":"en_US","og_type":"article","og_title":"Historical Timeline - Endowment","og_description":"Explore the University of Rochester\u2019s Endowment timeline and discover key milestones that have shaped its growth and impact since its founding.","og_url":"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/","og_site_name":"Endowment","article_modified_time":"2025-03-04T16:33:56+00:00","og_image":[{"url":"https:\/\/www.rochester.edu\/endowment\/wp-content\/uploads\/2025\/03\/Link-Preview-Endowment.png","width":1200,"height":630,"type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/","url":"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/","name":"Historical Timeline - Endowment","isPartOf":{"@id":"https:\/\/www.rochester.edu\/endowment\/#website"},"datePublished":"2025-02-27T16:14:29+00:00","dateModified":"2025-03-04T16:33:56+00:00","description":"Explore the University of Rochester\u2019s Endowment timeline and discover key milestones that have shaped its growth and impact since its founding.","breadcrumb":{"@id":"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rochester.edu\/endowment\/historical-timeline\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rochester.edu\/endowment\/historical-timeline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rochester.edu\/endowment\/"},{"@type":"ListItem","position":2,"name":"Historical Timeline"}]},{"@type":"WebSite","@id":"https:\/\/www.rochester.edu\/endowment\/#website","url":"https:\/\/www.rochester.edu\/endowment\/","name":"Endowment University of Rochester","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rochester.edu\/endowment\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.rochester.edu\/endowment\/wp-json\/wp\/v2\/pages\/4356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rochester.edu\/endowment\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rochester.edu\/endowment\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rochester.edu\/endowment\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rochester.edu\/endowment\/wp-json\/wp\/v2\/comments?post=4356"}],"version-history":[{"count":4,"href":"https:\/\/www.rochester.edu\/endowment\/wp-json\/wp\/v2\/pages\/4356\/revisions"}],"predecessor-version":[{"id":4396,"href":"https:\/\/www.rochester.edu\/endowment\/wp-json\/wp\/v2\/pages\/4356\/revisions\/4396"}],"wp:attachment":[{"href":"https:\/\/www.rochester.edu\/endowment\/wp-json\/wp\/v2\/media?parent=4356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}